{"id":11358,"date":"2019-09-24T14:23:48","date_gmt":"2019-09-24T14:23:48","guid":{"rendered":"https:\/\/dev.fiamitalia.it\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/"},"modified":"2023-02-21T14:31:21","modified_gmt":"2023-02-21T14:31:21","slug":"fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore","status":"publish","type":"post","link":"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/","title":{"rendered":"FIAM for Love Design &#8211; october 11th &#8211; 13th at Fabbrica del Vapore, Milan"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"11358\" class=\"elementor elementor-11358 elementor-11348\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ef0096e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ef0096e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-80f4a59\" data-id=\"80f4a59\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8a5207 elementor-widget elementor-widget-text-editor\" data-id=\"c8a5207\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tFiam Italia renovates its contribution for the ninth edition of the Love Design fundraising initiative. Love Design is a bi-annual event promoted by AIRC (Italian Foundation for Cancer Research) and ADI (Industrial Design Association) which will take place this year from the 11th to the 13th of October within the wide, prestigious Fabbrica del Vapore of Milan. Like in the past editions, Fiam Italia will take part to the initiative along with the most important Italian design companies and it will donate its products in order to raise funds for the cancer research. Love Design reveals itself once again as a date to save for over 15.000 people, who are going to help defeating the cancer beast with their taste for design.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>From 11th to 13th October, Fiam Italia will take part to the ninth edition of Love Design at Fabbrica del vapore<\/p>\n","protected":false},"author":1,"featured_media":11350,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-11358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>FIAM for Love Design - october 11th - 13th at Fabbrica del Vapore, Milan - Fiam Italia<\/title>\n<meta name=\"description\" content=\"From 11th to 13th October, Fiam Italia will take part to the ninth edition of Love Design at Fabbrica del vapore\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FIAM for Love Design - october 11th - 13th at Fabbrica del Vapore, Milan - Fiam Italia\" \/>\n<meta property=\"og:description\" content=\"From 11th to 13th October, Fiam Italia will take part to the ninth edition of Love Design at Fabbrica del vapore\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiam Italia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fiamitalia\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-24T14:23:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-21T14:31:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiamitalia.it\/wp-content\/uploads\/2023\/02\/Fiam_News_Love_deisgn.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"490\" \/>\n\t<meta property=\"og:image:height\" content=\"580\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"wk_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"wk_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/\"},\"author\":{\"name\":\"wk_admin\",\"@id\":\"https:\/\/www.fiamitalia.it\/en\/#\/schema\/person\/e9a13a97ed1e19a5ca25637abe75b6ea\"},\"headline\":\"FIAM for Love Design &#8211; october 11th &#8211; 13th at Fabbrica del Vapore, Milan\",\"datePublished\":\"2019-09-24T14:23:48+00:00\",\"dateModified\":\"2023-02-21T14:31:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/\"},\"wordCount\":135,\"publisher\":{\"@id\":\"https:\/\/www.fiamitalia.it\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiamitalia.it\/wp-content\/uploads\/2023\/02\/Fiam_News_Love_deisgn.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/\",\"url\":\"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/\",\"name\":\"FIAM for Love Design - october 11th - 13th at Fabbrica del Vapore, Milan - Fiam Italia\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiamitalia.it\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiamitalia.it\/wp-content\/uploads\/2023\/02\/Fiam_News_Love_deisgn.jpg\",\"datePublished\":\"2019-09-24T14:23:48+00:00\",\"dateModified\":\"2023-02-21T14:31:21+00:00\",\"description\":\"From 11th to 13th October, Fiam Italia will take part to the ninth edition of Love Design at Fabbrica del vapore\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/#primaryimage\",\"url\":\"https:\/\/www.fiamitalia.it\/wp-content\/uploads\/2023\/02\/Fiam_News_Love_deisgn.jpg\",\"contentUrl\":\"https:\/\/www.fiamitalia.it\/wp-content\/uploads\/2023\/02\/Fiam_News_Love_deisgn.jpg\",\"width\":490,\"height\":580},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiamitalia.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FIAM for Love Design &#8211; october 11th &#8211; 13th at Fabbrica del Vapore, Milan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiamitalia.it\/en\/#website\",\"url\":\"https:\/\/www.fiamitalia.it\/en\/\",\"name\":\"Fiam Italia\",\"description\":\"Da oltre 40 anni FIAM \u00e8 sinonimo di cultura del vetro a livello globale e produce elementi di arredo in vetro curvato di design. Scopri di pi\u00f9 sul sito!\",\"publisher\":{\"@id\":\"https:\/\/www.fiamitalia.it\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiamitalia.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiamitalia.it\/en\/#organization\",\"name\":\"Fiam Italia\",\"url\":\"https:\/\/www.fiamitalia.it\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.fiamitalia.it\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiamitalia.it\/wp-content\/uploads\/2023\/03\/cropped-Fiam_quadr_bn_Outline.png\",\"contentUrl\":\"https:\/\/www.fiamitalia.it\/wp-content\/uploads\/2023\/03\/cropped-Fiam_quadr_bn_Outline.png\",\"width\":945,\"height\":945,\"caption\":\"Fiam Italia\"},\"image\":{\"@id\":\"https:\/\/www.fiamitalia.it\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/fiamitalia\/\",\"https:\/\/www.instagram.com\/fiamitalia_official\/\",\"https:\/\/pinterest.com\/fiamitalia_\/\",\"https:\/\/www.linkedin.com\/company\/1658601\/\",\"https:\/\/www.youtube.com\/user\/FiamItalia\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiamitalia.it\/en\/#\/schema\/person\/e9a13a97ed1e19a5ca25637abe75b6ea\",\"name\":\"wk_admin\",\"sameAs\":[\"http:\/\/fiamitalia.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FIAM for Love Design - october 11th - 13th at Fabbrica del Vapore, Milan - Fiam Italia","description":"From 11th to 13th October, Fiam Italia will take part to the ninth edition of Love Design at Fabbrica del vapore","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/","og_locale":"en_US","og_type":"article","og_title":"FIAM for Love Design - october 11th - 13th at Fabbrica del Vapore, Milan - Fiam Italia","og_description":"From 11th to 13th October, Fiam Italia will take part to the ninth edition of Love Design at Fabbrica del vapore","og_url":"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/","og_site_name":"Fiam Italia","article_publisher":"https:\/\/www.facebook.com\/fiamitalia\/","article_published_time":"2019-09-24T14:23:48+00:00","article_modified_time":"2023-02-21T14:31:21+00:00","og_image":[{"width":490,"height":580,"url":"https:\/\/www.fiamitalia.it\/wp-content\/uploads\/2023\/02\/Fiam_News_Love_deisgn.jpg","type":"image\/jpeg"}],"author":"wk_admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"wk_admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/#article","isPartOf":{"@id":"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/"},"author":{"name":"wk_admin","@id":"https:\/\/www.fiamitalia.it\/en\/#\/schema\/person\/e9a13a97ed1e19a5ca25637abe75b6ea"},"headline":"FIAM for Love Design &#8211; october 11th &#8211; 13th at Fabbrica del Vapore, Milan","datePublished":"2019-09-24T14:23:48+00:00","dateModified":"2023-02-21T14:31:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/"},"wordCount":135,"publisher":{"@id":"https:\/\/www.fiamitalia.it\/en\/#organization"},"image":{"@id":"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiamitalia.it\/wp-content\/uploads\/2023\/02\/Fiam_News_Love_deisgn.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/","url":"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/","name":"FIAM for Love Design - october 11th - 13th at Fabbrica del Vapore, Milan - Fiam Italia","isPartOf":{"@id":"https:\/\/www.fiamitalia.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/#primaryimage"},"image":{"@id":"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiamitalia.it\/wp-content\/uploads\/2023\/02\/Fiam_News_Love_deisgn.jpg","datePublished":"2019-09-24T14:23:48+00:00","dateModified":"2023-02-21T14:31:21+00:00","description":"From 11th to 13th October, Fiam Italia will take part to the ninth edition of Love Design at Fabbrica del vapore","breadcrumb":{"@id":"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/#primaryimage","url":"https:\/\/www.fiamitalia.it\/wp-content\/uploads\/2023\/02\/Fiam_News_Love_deisgn.jpg","contentUrl":"https:\/\/www.fiamitalia.it\/wp-content\/uploads\/2023\/02\/Fiam_News_Love_deisgn.jpg","width":490,"height":580},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiamitalia.it\/en\/fiam-per-love-design-dall-11-al-13-ottobre-2019-alla-fabbrica-del-vafiam-italia-partecipa-alla-nona-edizione-di-love-design-dall11-al-13-ottobre-alla-fabbrica-del-vaporepore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiamitalia.it\/en\/"},{"@type":"ListItem","position":2,"name":"FIAM for Love Design &#8211; october 11th &#8211; 13th at Fabbrica del Vapore, Milan"}]},{"@type":"WebSite","@id":"https:\/\/www.fiamitalia.it\/en\/#website","url":"https:\/\/www.fiamitalia.it\/en\/","name":"Fiam Italia","description":"Da oltre 40 anni FIAM \u00e8 sinonimo di cultura del vetro a livello globale e produce elementi di arredo in vetro curvato di design. Scopri di pi\u00f9 sul sito!","publisher":{"@id":"https:\/\/www.fiamitalia.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiamitalia.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.fiamitalia.it\/en\/#organization","name":"Fiam Italia","url":"https:\/\/www.fiamitalia.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fiamitalia.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiamitalia.it\/wp-content\/uploads\/2023\/03\/cropped-Fiam_quadr_bn_Outline.png","contentUrl":"https:\/\/www.fiamitalia.it\/wp-content\/uploads\/2023\/03\/cropped-Fiam_quadr_bn_Outline.png","width":945,"height":945,"caption":"Fiam Italia"},"image":{"@id":"https:\/\/www.fiamitalia.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fiamitalia\/","https:\/\/www.instagram.com\/fiamitalia_official\/","https:\/\/pinterest.com\/fiamitalia_\/","https:\/\/www.linkedin.com\/company\/1658601\/","https:\/\/www.youtube.com\/user\/FiamItalia\/"]},{"@type":"Person","@id":"https:\/\/www.fiamitalia.it\/en\/#\/schema\/person\/e9a13a97ed1e19a5ca25637abe75b6ea","name":"wk_admin","sameAs":["http:\/\/fiamitalia.it"]}]}},"_links":{"self":[{"href":"https:\/\/www.fiamitalia.it\/en\/wp-json\/wp\/v2\/posts\/11358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiamitalia.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiamitalia.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiamitalia.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiamitalia.it\/en\/wp-json\/wp\/v2\/comments?post=11358"}],"version-history":[{"count":4,"href":"https:\/\/www.fiamitalia.it\/en\/wp-json\/wp\/v2\/posts\/11358\/revisions"}],"predecessor-version":[{"id":11363,"href":"https:\/\/www.fiamitalia.it\/en\/wp-json\/wp\/v2\/posts\/11358\/revisions\/11363"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fiamitalia.it\/en\/wp-json\/wp\/v2\/media\/11350"}],"wp:attachment":[{"href":"https:\/\/www.fiamitalia.it\/en\/wp-json\/wp\/v2\/media?parent=11358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiamitalia.it\/en\/wp-json\/wp\/v2\/categories?post=11358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiamitalia.it\/en\/wp-json\/wp\/v2\/tags?post=11358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}